{"id":52354,"date":"2025-12-26T09:56:44","date_gmt":"2025-12-26T12:56:44","guid":{"rendered":"https:\/\/infoactual.com.ar\/?p=52354"},"modified":"2025-12-26T09:56:51","modified_gmt":"2025-12-26T12:56:51","slug":"la-produccion-de-acero-crudo-crecio-un-04-en-noviembre-y-107-interanual","status":"publish","type":"post","link":"https:\/\/infoactual.com.ar\/index.php\/2025\/12\/26\/la-produccion-de-acero-crudo-crecio-un-04-en-noviembre-y-107-interanual\/","title":{"rendered":"La producci\u00f3n de acero crudo creci\u00f3 un 0,4% en noviembre y 10,7% interanual"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Con un total de 374.900 toneladas, la producci\u00f3n de acero crudo tuvo un incremento del 0,4% con respecto al mes de octubre \u00faltimo y un incremento del 10,7% comparado con el mismo mes del 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, la producci\u00f3n de laminados (planos y no planos) fue de 334.300 toneladas, lo que represent\u00f3 una ca\u00edda del 1,1% respecto del mes anterior y una suba del 0,7% interanual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a la actividad de los sectores demandantes del acero:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El\u00a0<strong>sector de la construcci\u00f3n<\/strong>\u00a0contin\u00faa sin recuperarse y con amplias variaciones. Los despachos de cemento durante el mes de noviembre mostraron una ca\u00edda del 13,7% respecto de octubre \u00faltimo. En la comparaci\u00f3n contra el mismo mes del a\u00f1o anterior se puede apreciar una ca\u00edda del 4,2%.<\/li>\n\n\n\n<li>En el\u00a0<strong>sector automotor<\/strong>, la producci\u00f3n de noviembre registr\u00f3 una baja del 19,6% respecto de octubre y un descenso del 29,3% con relaci\u00f3n a igual mes del a\u00f1o anterior. Comparando 11 meses del 2025 con respecto al 2024 se registr\u00f3 una baja del 0,9%.<\/li>\n\n\n\n<li>El\u00a0<strong>sector de maquinaria e implementos agr\u00edcolas<\/strong>\u00a0est\u00e1 cerrando 2025 con una tendencia a la desaceleraci\u00f3n, aunque el saldo total del a\u00f1o es ligeramente superior al 2024. Las proyecciones para 2026 se basan en la potencial reactivaci\u00f3n que traer\u00eda un escenario econ\u00f3mico m\u00e1s estable y una buena cosecha<\/li>\n\n\n\n<li>En los\u00a0<strong>sectores vinculados al consumo masivo<\/strong>\u00a0como el sector de l\u00ednea blanca, est\u00e1 finalizando el 2025 en un momento cr\u00edtico, con fuerte ca\u00edda de volumen, sobreoferta y presi\u00f3n importadora. La esperanza de recuperaci\u00f3n en 2026 se basa casi exclusivamente en la normalizaci\u00f3n del cr\u00e9dito y la mejora del ingreso.<\/li>\n\n\n\n<li>El\u00a0<strong>sector energ\u00eda<\/strong>\u00a0cierra 2025 con demanda ascendente en las \u00e1reas ligadas a Vaca Muerta, debido a la entrada en operaci\u00f3n de proyectos de transporte de hidrocarburos que resuelven los \u201ccuellos de botella\u201d del sistema. Se espera para 2026 que se lancen nuevos proyectos, para los cuales la presi\u00f3n importadora puede impactar fuertemente en la provisi\u00f3n local de insumos de acero.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Con un total de 374.900 toneladas, la producci\u00f3n de acero crudo tuvo un incremento del 0,4% con respecto al mes de octubre \u00faltimo y un incremento del 10,7% comparado con el mismo mes del 2024. Por su parte, la producci\u00f3n de laminados (planos y no planos) fue de 334.300 toneladas, lo que represent\u00f3 una ca\u00edda [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":52355,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[44],"tags":[],"class_list":["post-52354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia"],"_links":{"self":[{"href":"https:\/\/infoactual.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/52354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infoactual.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infoactual.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infoactual.com.ar\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infoactual.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=52354"}],"version-history":[{"count":1,"href":"https:\/\/infoactual.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/52354\/revisions"}],"predecessor-version":[{"id":52356,"href":"https:\/\/infoactual.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/52354\/revisions\/52356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infoactual.com.ar\/index.php\/wp-json\/wp\/v2\/media\/52355"}],"wp:attachment":[{"href":"https:\/\/infoactual.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=52354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infoactual.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=52354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infoactual.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=52354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}